{"id":222,"count":1,"description":"","link":"https:\/\/reisen-travel.com\/reise-angebote\/tag\/familienfreundliche-hotels\/","name":"Familienfreundliche Hotels","slug":"familienfreundliche-hotels","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/reisen-travel.com\/reise-angebote\/wp-json\/wp\/v2\/tags\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reisen-travel.com\/reise-angebote\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/reisen-travel.com\/reise-angebote\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/reisen-travel.com\/reise-angebote\/wp-json\/wp\/v2\/posts?tags=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}